{"id":7207,"date":"2022-09-29T15:34:12","date_gmt":"2022-09-29T13:34:12","guid":{"rendered":"https:\/\/viablue.laolaweb.com\/kataloge\/"},"modified":"2024-05-24T10:45:30","modified_gmt":"2024-05-24T08:45:30","slug":"catalogs","status":"publish","type":"page","link":"https:\/\/viablue.de\/en\/catalogs\/","title":{"rendered":"Catalogs"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"7207\" class=\"elementor elementor-7207 elementor-282\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7ea75e58 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7ea75e58\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-756a60e9\" data-id=\"756a60e9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-822923e elementor-invisible elementor-widget elementor-widget-jet-headline\" data-id=\"822923e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"jet-headline.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"jet-headline jet-headline--direction-horizontal\"><span class=\"jet-headline__part jet-headline__first\"><span class=\"jet-headline__label\">Catalogs &amp;<\/span><\/span><span class=\"jet-headline__space\">&nbsp;<\/span><span class=\"jet-headline__part jet-headline__second\"><span class=\"jet-headline__label\">Manuals<\/span><\/span><\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-68edc4a7 elementor-invisible elementor-widget elementor-widget-jet-headline\" data-id=\"68edc4a7\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"jet-headline.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"jet-headline jet-headline--direction-horizontal\"><span class=\"jet-headline__part jet-headline__first\"><span class=\"jet-headline__label\">High-End<\/span><\/span><span class=\"jet-headline__space\">&nbsp;<\/span><span class=\"jet-headline__part jet-headline__second\"><span class=\"jet-headline__label\">Technologies<\/span><\/span><\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-22d72556 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"22d72556\" data-element_type=\"section\" data-e-type=\"section\" id=\"kataloge\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2f153ff4\" data-id=\"2f153ff4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5ac94244 elementor-widget elementor-widget-heading\" data-id=\"5ac94244\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"single-wire\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Catalogs<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1aa9c5aa elementor-widget elementor-widget-jet-listing-grid\" data-id=\"1aa9c5aa\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;columns&quot;:&quot;2&quot;,&quot;columns_mobile&quot;:&quot;1&quot;}\" data-widget_type=\"jet-listing-grid.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"jet-listing-grid jet-listing\"><div class=\"jet-listing-not-found jet-listing-grid__items\" data-nav=\"{&quot;enabled&quot;:false,&quot;type&quot;:null,&quot;more_el&quot;:null,&quot;query&quot;:[],&quot;widget_settings&quot;:{&quot;lisitng_id&quot;:291,&quot;posts_num&quot;:6,&quot;columns&quot;:2,&quot;columns_tablet&quot;:2,&quot;columns_mobile&quot;:1,&quot;column_min_width&quot;:240,&quot;column_min_width_tablet&quot;:240,&quot;column_min_width_mobile&quot;:240,&quot;inline_columns_css&quot;:false,&quot;is_archive_template&quot;:&quot;&quot;,&quot;post_status&quot;:[&quot;publish&quot;],&quot;use_random_posts_num&quot;:&quot;&quot;,&quot;max_posts_num&quot;:9,&quot;not_found_message&quot;:&quot;Keine Ergebnisse...&quot;,&quot;is_masonry&quot;:false,&quot;equal_columns_height&quot;:&quot;&quot;,&quot;use_load_more&quot;:&quot;&quot;,&quot;load_more_id&quot;:&quot;&quot;,&quot;load_more_type&quot;:&quot;click&quot;,&quot;load_more_offset&quot;:null,&quot;use_custom_post_types&quot;:&quot;&quot;,&quot;custom_post_types&quot;:[],&quot;hide_widget_if&quot;:&quot;&quot;,&quot;carousel_enabled&quot;:&quot;&quot;,&quot;slides_to_scroll&quot;:&quot;1&quot;,&quot;arrows&quot;:&quot;true&quot;,&quot;arrow_icon&quot;:&quot;fa fa-angle-left&quot;,&quot;dots&quot;:&quot;&quot;,&quot;autoplay&quot;:&quot;true&quot;,&quot;pause_on_hover&quot;:&quot;true&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;true&quot;,&quot;center_mode&quot;:&quot;&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500,&quot;inject_alternative_items&quot;:&quot;&quot;,&quot;injection_items&quot;:[],&quot;scroll_slider_enabled&quot;:&quot;&quot;,&quot;scroll_slider_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;custom_query&quot;:false,&quot;custom_query_id&quot;:&quot;&quot;,&quot;_element_id&quot;:&quot;&quot;,&quot;collapse_first_last_gap&quot;:false,&quot;list_tag_selection&quot;:&quot;&quot;,&quot;list_items_wrapper_tag&quot;:&quot;div&quot;,&quot;list_item_tag&quot;:&quot;div&quot;,&quot;empty_items_wrapper_tag&quot;:&quot;div&quot;}}\" data-listing-source=\"posts\" data-listing-id=\"291\" data-query-id=\"\" data-queried-id=\"7207|WP_Post\">Keine Ergebnisse...<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7ec8a5a9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7ec8a5a9\" data-element_type=\"section\" data-e-type=\"section\" id=\"anleitungen\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1de3d8e2\" data-id=\"1de3d8e2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4b605616 elementor-widget elementor-widget-heading\" data-id=\"4b605616\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"bi-wire\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Manuals<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b68f8f6 elementor-widget elementor-widget-jet-listing-grid\" data-id=\"b68f8f6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;columns&quot;:&quot;2&quot;,&quot;columns_mobile&quot;:&quot;1&quot;}\" data-widget_type=\"jet-listing-grid.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"jet-listing-grid jet-listing\"><div class=\"jet-listing-grid__items grid-col-desk-2 grid-col-tablet-2 grid-col-mobile-1 jet-listing-grid--291\" data-queried-id=\"7207|WP_Post\" data-nav=\"{&quot;enabled&quot;:false,&quot;type&quot;:null,&quot;more_el&quot;:null,&quot;query&quot;:[],&quot;widget_settings&quot;:{&quot;lisitng_id&quot;:291,&quot;posts_num&quot;:6,&quot;columns&quot;:2,&quot;columns_tablet&quot;:2,&quot;columns_mobile&quot;:1,&quot;column_min_width&quot;:240,&quot;column_min_width_tablet&quot;:240,&quot;column_min_width_mobile&quot;:240,&quot;inline_columns_css&quot;:false,&quot;is_archive_template&quot;:&quot;&quot;,&quot;post_status&quot;:[&quot;publish&quot;],&quot;use_random_posts_num&quot;:&quot;&quot;,&quot;max_posts_num&quot;:9,&quot;not_found_message&quot;:&quot;Keine Ergebnisse...&quot;,&quot;is_masonry&quot;:false,&quot;equal_columns_height&quot;:&quot;&quot;,&quot;use_load_more&quot;:&quot;&quot;,&quot;load_more_id&quot;:&quot;&quot;,&quot;load_more_type&quot;:&quot;click&quot;,&quot;load_more_offset&quot;:null,&quot;use_custom_post_types&quot;:&quot;&quot;,&quot;custom_post_types&quot;:[],&quot;hide_widget_if&quot;:&quot;&quot;,&quot;carousel_enabled&quot;:&quot;&quot;,&quot;slides_to_scroll&quot;:&quot;1&quot;,&quot;arrows&quot;:&quot;true&quot;,&quot;arrow_icon&quot;:&quot;fa fa-angle-left&quot;,&quot;dots&quot;:&quot;&quot;,&quot;autoplay&quot;:&quot;true&quot;,&quot;pause_on_hover&quot;:&quot;true&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;true&quot;,&quot;center_mode&quot;:&quot;&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500,&quot;inject_alternative_items&quot;:&quot;&quot;,&quot;injection_items&quot;:[],&quot;scroll_slider_enabled&quot;:&quot;&quot;,&quot;scroll_slider_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;custom_query&quot;:false,&quot;custom_query_id&quot;:&quot;&quot;,&quot;_element_id&quot;:&quot;&quot;,&quot;collapse_first_last_gap&quot;:false,&quot;list_tag_selection&quot;:&quot;&quot;,&quot;list_items_wrapper_tag&quot;:&quot;div&quot;,&quot;list_item_tag&quot;:&quot;div&quot;,&quot;empty_items_wrapper_tag&quot;:&quot;div&quot;}}\" data-page=\"1\" data-pages=\"1\" data-listing-source=\"posts\" data-listing-id=\"291\" data-query-id=\"\"><div class=\"jet-listing-grid__item jet-listing-dynamic-post-16272 elementor-dcss-17949878595052880\" data-post-id=\"16272\"  ><div class=\"jet-engine-listing-overlay-wrap\" data-url=\"https:\/\/viablue.de\/wp-content\/uploads\/2024\/05\/VIABLUE-TECH-GUIDE-CABLE-LIFTER-ENG-2024-1.pdf\" data-target=\"_blank\">\t\t<div data-elementor-type=\"jet-listing-items\" data-elementor-id=\"291\" class=\"elementor elementor-291\" data-elementor-post-type=\"jet-engine\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b942ace elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b942ace\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-65d3bdd\" data-id=\"65d3bdd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-15e3099 elementor-widget elementor-widget-image\" data-id=\"15e3099\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"768\" height=\"662\" src=\"https:\/\/viablue.de\/wp-content\/uploads\/2024\/05\/Deckblatt-CLTG-ENG-768x662.jpg\" class=\"attachment-medium_large size-medium_large wp-image-16271\" alt=\"\" srcset=\"https:\/\/viablue.de\/wp-content\/uploads\/2024\/05\/Deckblatt-CLTG-ENG-768x662.jpg 768w, https:\/\/viablue.de\/wp-content\/uploads\/2024\/05\/Deckblatt-CLTG-ENG-300x259.jpg 300w, https:\/\/viablue.de\/wp-content\/uploads\/2024\/05\/Deckblatt-CLTG-ENG-1024x883.jpg 1024w, https:\/\/viablue.de\/wp-content\/uploads\/2024\/05\/Deckblatt-CLTG-ENG.jpg 1492w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6fbee43\" data-id=\"6fbee43\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2390b4b elementor-widget elementor-widget-jet-headline\" data-id=\"2390b4b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jet-headline.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"jet-headline jet-headline--direction-horizontal\"><span class=\"jet-headline__part jet-headline__first\"><span class=\"jet-headline__label\">Cable Lifter Technical Guide<\/span><\/span><span class=\"jet-headline__space\">&nbsp;<\/span><span class=\"jet-headline__part jet-headline__second\"><span class=\"jet-headline__label\">englisch<\/span><\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2499a71 elementor-widget elementor-widget-jet-listing-dynamic-field\" data-id=\"2499a71\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jet-listing-dynamic-field.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"jet-listing jet-listing-dynamic-field display-inline\"><div class=\"jet-listing-dynamic-field__inline-wrap\"><div class=\"jet-listing-dynamic-field__content\" ><p>For Cable Lifter<\/p>\n<\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<a href=\"https:\/\/viablue.de\/wp-content\/uploads\/2024\/05\/VIABLUE-TECH-GUIDE-CABLE-LIFTER-ENG-2024-1.pdf\" class=\"jet-engine-listing-overlay-link\" target=\"_blank\"><\/a><\/div><\/div><div class=\"jet-listing-grid__item jet-listing-dynamic-post-5311 elementor-dcss-17949878665213668\" data-post-id=\"5311\"  ><div class=\"jet-engine-listing-overlay-wrap\" data-url=\"https:\/\/viablue.de\/wp-content\/uploads\/2025\/09\/VIABLUE-SetUp-Guide-deutsch-2025-12.pdf\" data-target=\"_blank\">\t\t<div data-elementor-type=\"jet-listing-items\" data-elementor-id=\"291\" class=\"elementor elementor-291\" data-elementor-post-type=\"jet-engine\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b942ace elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b942ace\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-65d3bdd\" data-id=\"65d3bdd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-15e3099 elementor-widget elementor-widget-image\" data-id=\"15e3099\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"600\" height=\"517\" src=\"https:\/\/viablue.de\/wp-content\/uploads\/2022\/10\/Spikes-and-Absorbers-download-image-manual-SetUP-Guide-VIABLUE.jpg\" class=\"attachment-medium_large size-medium_large wp-image-13391\" alt=\"Spikes and Absorbers download image manual SetUP-Guide VIABLUE\" srcset=\"https:\/\/viablue.de\/wp-content\/uploads\/2022\/10\/Spikes-and-Absorbers-download-image-manual-SetUP-Guide-VIABLUE.jpg 600w, https:\/\/viablue.de\/wp-content\/uploads\/2022\/10\/Spikes-and-Absorbers-download-image-manual-SetUP-Guide-VIABLUE-300x259.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6fbee43\" data-id=\"6fbee43\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2390b4b elementor-widget elementor-widget-jet-headline\" data-id=\"2390b4b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jet-headline.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"jet-headline jet-headline--direction-horizontal\"><span class=\"jet-headline__part jet-headline__first\"><span class=\"jet-headline__label\">Set-up Guide<\/span><\/span><span class=\"jet-headline__space\">&nbsp;<\/span><span class=\"jet-headline__part jet-headline__second\"><span class=\"jet-headline__label\">German<\/span><\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2499a71 elementor-widget elementor-widget-jet-listing-dynamic-field\" data-id=\"2499a71\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jet-listing-dynamic-field.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"jet-listing jet-listing-dynamic-field display-inline\"><div class=\"jet-listing-dynamic-field__inline-wrap\"><div class=\"jet-listing-dynamic-field__content\" ><div class=\"content\">\n<p>For spikes &amp; absorbers<\/p>\n<\/div>\n<\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<a href=\"https:\/\/viablue.de\/wp-content\/uploads\/2025\/09\/VIABLUE-SetUp-Guide-deutsch-2025-12.pdf\" class=\"jet-engine-listing-overlay-link\" target=\"_blank\"><\/a><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Catalogs &#038;&nbsp;Manuals High-End&nbsp;Technologies Catalogs 2023\/2024 2023\/2024 Manuals For Cable Lifter For spikes &amp; absorbers For spikes &amp; absorbers<\/p>\n","protected":false},"author":6,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"footnotes":""},"class_list":["post-7207","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/viablue.de\/en\/wp-json\/wp\/v2\/pages\/7207","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/viablue.de\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/viablue.de\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/viablue.de\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/viablue.de\/en\/wp-json\/wp\/v2\/comments?post=7207"}],"version-history":[{"count":7,"href":"https:\/\/viablue.de\/en\/wp-json\/wp\/v2\/pages\/7207\/revisions"}],"predecessor-version":[{"id":16279,"href":"https:\/\/viablue.de\/en\/wp-json\/wp\/v2\/pages\/7207\/revisions\/16279"}],"wp:attachment":[{"href":"https:\/\/viablue.de\/en\/wp-json\/wp\/v2\/media?parent=7207"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}